{"id":50,"date":"2019-04-17T20:13:00","date_gmt":"2019-04-17T20:13:00","guid":{"rendered":"http:\/\/tierra.local\/?p=50"},"modified":"2021-05-01T20:01:42","modified_gmt":"2021-05-01T20:01:42","slug":"el-hatillo-la-tensa-lucha-por-no-respirar-carbon","status":"publish","type":"post","link":"https:\/\/tierraderesistentes.com\/es\/2019\/04\/17\/el-hatillo-la-tensa-lucha-por-no-respirar-carbon\/","title":{"rendered":"El Hatillo, la tensa lucha por no respirar carb\u00f3n"},"content":{"rendered":"\n<p class=\"has-text-color has-small-font-size\" style=\"color:#0f0f0f;max-width:830px;margin-top:0px;margin-bottom:68px\"><em><strong>En el departamento de Cesar, en el nororiente colombiano, una comunidad campesina lleva casi una d\u00e9cada esperando ser reasentada a causa de la contaminaci\u00f3n generada por las minas aleda\u00f1as. En los \u00faltimos cuatro a\u00f1os, un l\u00edder fue asesinado y ocho m\u00e1s han recibido amenazas.<\/strong><\/em><\/p>\n\n\n\n<p>Quien vaya a El Hatillo encontrar\u00e1 que es un pueblo dejado a su suerte. <strong>La comunidad lleva el mismo nombre de una mina de carb\u00f3n que el Gobierno concesion\u00f3 hace 22 a\u00f1os sin que los campesinos supieran<\/strong> (<a rel=\"noreferrer noopener\" href=\"https:\/\/es.scribd.com\/document\/404327718\/Documento-Historia-Hatillo-Autoridad-Nacional-de-Licencias-Ambientales?secret_password=0dPEtlO72vS8hFrclMDD\" target=\"_blank\">ver p\u00e1gina 11 del documento<\/a>).<\/p>\n\n\n\n<p>De la \u00e9poca agr\u00edcola solo les queda el recuerdo. No tienen agua potable, ni v\u00edas pavimentadas, las casas en su mayor\u00eda son de barro y palos. <strong>La poca infraestructura y oportunidades laborales en la zona dependen de las tres empresas mineras con las que han tenido que negociar su reasentamiento.<\/strong> Este \u00faltimo fue&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/es.scribd.com\/document\/404327772\/Resolucio-n-1525-del-5-de-agosto-de-2010?secret_password=eIPMQHdbTTk7cAEq6YLT\" target=\"_blank\">ordenado<\/a>&nbsp;por el Ministerio de Ambiente desde el a\u00f1o 2010, tras concluir que la explotaci\u00f3n de carb\u00f3n afectaba a esta poblaci\u00f3n as\u00ed como a las comunidades vecinas de Plan Bonito y Boquer\u00f3n.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cAc\u00e1 el Estado nos dej\u00f3 solos\u201d<\/p><\/blockquote>\n\n\n\n<p>\u201cAc\u00e1 el Estado nos dej\u00f3 solos\u201d, repiten los campesinos, describiendo el reasentamiento como un proceso que les arrebat\u00f3 la tranquilidad y los mantiene en vilo.<\/p>\n\n\n\n<p>Por eso en este poblado a dos horas de Valledupar, la capital del Cesar, la comunidad cuida sus palabras.<\/p>\n\n\n\n<figure class=\"wp-block-image alignfull size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/tierra.jerre-dev.xyz\/wp-content\/uploads\/2019\/04\/CYD_6774-scaled.jpg\" alt=\"\" class=\"wp-image-4872\" srcset=\"https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211243\/CYD_6774-scaled.jpg 2560w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211243\/CYD_6774-300x200.jpg 300w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211243\/CYD_6774-1024x683.jpg 1024w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211243\/CYD_6774-768x512.jpg 768w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211243\/CYD_6774-1536x1024.jpg 1536w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211243\/CYD_6774-2048x1365.jpg 2048w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211243\/CYD_6774-150x100.jpg 150w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211243\/CYD_6774-696x464.jpg 696w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211243\/CYD_6774-1068x712.jpg 1068w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211243\/CYD_6774-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<p>Son pocos los que quieren hablar del asesinato de Aldemar Parra Garc\u00eda, ocurrido el 7 de enero de 2017, y de las amenazas que comenzaron en el 2014 contra los l\u00edderes que participaban en las mesas de concertaci\u00f3n con las empresas mineras. El riesgo se intensific\u00f3 en el 2016 cuando presentaron una acci\u00f3n de tutela por la demora en el reasentamiento, al punto que la Defensor\u00eda del Pueblo -la entidad a cargo de velar por los derechos humanos de los colombianos- incluy\u00f3 sus nombres&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/es.scribd.com\/document\/404327760\/Informe-de-riesgo-Defensori-a-28-de-noviembre-2016?secret_password=5vPp1j8WmqxwxieoqbLC\" target=\"_blank\">en el informe<\/a>&nbsp;que alert\u00f3 sobre la vulnerabilidad de 80 l\u00edderes sociales de la regi\u00f3n.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cEl peligro es latente\u201d<\/p><\/blockquote>\n\n\n\n<p><strong>La situaci\u00f3n no mejor\u00f3.<\/strong> \u201cEl peligro es latente\u201d, afirma uno de los ocho l\u00edderes que cuenta con un esquema de protecci\u00f3n provisto por el Estado colombiano, quien pide no revelar su nombre por temor.<\/p>\n\n\n\n<p><strong>Durante los pr\u00f3ximos cinco a\u00f1os la comunidad entrar\u00e1 en un nuevo proceso: la implementaci\u00f3n del llamado Plan de Acci\u00f3n de Reasentamiento (PAR)<\/strong>, un documento que les tom\u00f3 seis a\u00f1os de negociaci\u00f3n con las mineras y que finalmente firmaron el 29 de noviembre de 2018. Para los l\u00edderes de Hatillo, lo fundamental es que los compromisos pactados en sus 700 p\u00e1ginas no queden en el papel y, sobre todo, que existan garant\u00edas de seguridad para reconstruir sus vidas en otro lugar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El campo que no fue<\/h2>\n\n\n\n<p>Jos\u00e9 del Carmen Correa habla con nostalgia mientras camina por las calles destartaladas y polvorientas de El Hatillo.<\/p>\n\n\n\n<p>Es hatillano y evoca escenas de su infancia, corriendo con libertad por ese campo verde que de un lado es un cr\u00e1ter y del otro, una monta\u00f1a de sedimentos que crece con la explotaci\u00f3n del carb\u00f3n. Es descendiente de colonos que llegaron a esta zona en el siglo pasado para cultivar ma\u00edz, pl\u00e1tano, algod\u00f3n, sin que les preocupara si ten\u00edan o no t\u00edtulos de propiedad sobre la tierra. <strong>Por tratarse de bald\u00edos -o tierras de la Naci\u00f3n- ten\u00edan derecho a pedirlas en adjudicaci\u00f3n tras algunos a\u00f1os de trabajo, pero los campesinos viv\u00edan entonces tranquilos cultivando su alimento, criando animales y pescando en el r\u00edo Calenturitas.&nbsp;<\/strong><\/p>\n\n\n\n<figure><iframe loading=\"lazy\" width=\"480\" height=\"270\" src=\"https:\/\/www.youtube.com\/embed\/SySRug9h-iw?feature=oembed\" allowfullscreen=\"\"><\/iframe><\/figure>\n\n\n\n<p><strong>Ese paisaje agr\u00edcola cambi\u00f3 a finales de la d\u00e9cada de los 80, cuando el Gobierno colombiano concesion\u00f3 gran parte de las tierras para la miner\u00eda y comenz\u00f3 el auge de&nbsp; la palma africana de aceite.<\/strong><\/p>\n\n\n\n<p>Hoy El Hatillo est\u00e1 rodeada no solo por la mina que lleva ese nombre, sino por otras cuatro m\u00e1s: las de Calenturitas, La Francia, El Descanso y Pribbenow-La Loma. Su explotaci\u00f3n ha convertido al centro del Cesar en la primera regi\u00f3n con mayor producci\u00f3n de carb\u00f3n en Colombia, con <strong>exportaciones principalmente a Turqu\u00eda, Corea del Sur, Brasil, Israel, Chile, Estados Unidos, Espa\u00f1a, Polonia, Puerto Rico y Portugal<\/strong>, seg\u00fan datos del Ministerio de Minas y Energ\u00eda (Ver&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/es.scribd.com\/document\/404327721\/Respuesta-Ministerio-de-Minas-y-Energi-a?secret_password=mHthKDw9FCb6pdHYalCX\" target=\"_blank\">respuesta del Ministerio de Minas<\/a>).<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Su explotaci\u00f3n ha convertido al centro del Cesar en la primera regi\u00f3n con mayor producci\u00f3n de carb\u00f3n en Colombia<\/p><\/blockquote>\n\n\n\n<p>La primera de ellas la opera Prodeco, filial de la multinacional anglo-suiza Glencore Xstrata. La segunda es propiedad de Colombian Natural Resources (CNR), que pertenec\u00eda al banco de inversi\u00f3n Goldman Sachs y fue vendido al Murray Energy Group en el 2015. Y las dos \u00faltimas son de la minera estadounidense Drummond. La mina hom\u00f3nima de El Hatillo ha rotado por varios due\u00f1os: la Empresa Promotora y Explotadora de Carb\u00f3n del Cesar y La Guajira (Emcarb\u00f3n), Carbones del Caribe (hoy Sator, del Grupo Argos), la brasile\u00f1a Vale Do Rio Doce y luego CNR. Al igual que la mina La Francia, la mina El Hatillo fue comprada por Murray Energy Group en el 2015, pero sigui\u00f3 operando bajo el nombre de CNR (<a rel=\"noreferrer noopener\" href=\"https:\/\/www.scribd.com\/document\/406394764\/Informacio-n-sobre-minas-de-carbo-n-Agencia-Nacional-de-Mineri-a\" target=\"_blank\">Ver informaci\u00f3n de minas, Agencia Nacional de Miner\u00eda<\/a>).&nbsp;<\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/cdn.knightlab.com\/libs\/timeline3\/latest\/embed\/index.html?source=1o0SHnWe_2ECmi5QZq7HU3iBM7HYs1e84DuQSYYcDkRs&#038;font=Default&#038;lang=es&#038;timenav_position=top&#038;initial_zoom=0&#038;height=400\" width=\"100%\" height=\"400\" allowfullscreen=\"\" style=\"border:none;\"><\/iframe>\n<span style=\"font-size:0.8em;\">HECHOS DE VIOLENCIA DESARROLLO MINERO.<\/span><br><br>\n\n\n\n<p>Su \u00fanico vecino no minero es<span style=\"background-color:#374141\" class=\"td_text_highlight_marker\"> Palmagro S.A.<\/span>, antes llamado Palmeras de Alamosa Ltda, que <strong>desde 1991 opera en un predio aleda\u00f1o una planta extractora para procesar el fruto de la palma de aceite usado en industrias como la cosm\u00e9tica y alimenticia.<\/strong><\/p>\n\n\n\n<p><strong>Para los pobladores, la miner\u00eda y la agroindustria han sido las responsables no solo de los cambios en el uso del suelo, sino tambi\u00e9n de la contaminaci\u00f3n del aire y los cuerpos de agua que los ha acompa\u00f1ado.<\/strong> Ya no hay c\u00f3mo alimentarse de los cultivos porque, cuentan, la tierra se volvi\u00f3 inf\u00e9rtil. Tampoco pueden cazar zainos, loches, venados, conejos, armadillos, chig\u00fciros o \u00f1eques, ni pescar bagres, bocachicos, comelones ni barbudos. Desaparecieron todos. El ca\u00f1ito de Piedra y los manantiales cercanos se secaron, y el r\u00edo Calenturitas fue desviado, con autorizaci\u00f3n del Ministerio de Ambiente, para favorecer a la industria del carb\u00f3n (<a rel=\"noreferrer noopener\" href=\"https:\/\/es.scribd.com\/document\/404327710\/Ministerio-Ambiente-Ri-o-Calenturitas?secret_password=Xx0kp3hi8fwhwIXb71Yj\" target=\"_blank\">Ver auto del Ministerio de Ambiente).<\/a><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abEra una comunidad cien por ciento campesina. Con la llegada de la miner\u00eda pues todo cambi\u00f3\u00bb.<\/p><cite>Deiby Rojas<\/cite><\/blockquote>\n\n\n\n<p>\u201cLa vocaci\u00f3n de la vereda era la pesquer\u00eda y la cacer\u00eda y se trabajaba en las fincas aleda\u00f1as que se dedicaban al ganado. Era una comunidad cien por ciento campesina. Con la llegada de la miner\u00eda pues todo cambi\u00f3\u201d, dice Deiby Rojas, tesorera de la Junta de Acci\u00f3n Comunal local.<\/p>\n\n\n\n<figure class=\"wp-block-image alignfull size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/tierra.jerre-dev.xyz\/wp-content\/uploads\/2019\/04\/CYD_6723-scaled.jpg\" alt=\"\" class=\"wp-image-4869\" srcset=\"https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211252\/CYD_6723-scaled.jpg 2560w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211252\/CYD_6723-300x200.jpg 300w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211252\/CYD_6723-1024x683.jpg 1024w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211252\/CYD_6723-768x512.jpg 768w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211252\/CYD_6723-1536x1024.jpg 1536w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211252\/CYD_6723-2048x1365.jpg 2048w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211252\/CYD_6723-150x100.jpg 150w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211252\/CYD_6723-696x464.jpg 696w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211252\/CYD_6723-1068x712.jpg 1068w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211252\/CYD_6723-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<p>Con estos cambios tambi\u00e9n <strong>comenzaron los problemas de salud<\/strong>. Miriam Jaimes, conciliadora de la junta local, explica que se han vuelto constantes las infecciones respiratorias en ni\u00f1os y adultos mayores, y una peste que ataca a los pocos animales de corral que pueden criar.<\/p>\n\n\n\n<p>\u201cHay mucha contaminaci\u00f3n y han salido muchas enfermedades en los pulmones. A los animales tambi\u00e9n, a los cerdos les da una peste y se mueren; a las gallinas, lo mismo\u201d, apunta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La larga espera<\/h2>\n\n\n\n<p><strong>Esa contaminaci\u00f3n de la que hablan los campesinos es el origen de sus luchas.&nbsp;<\/strong><\/p>\n\n\n\n<p>El Hatillo est\u00e1 a 10 minutos en motocarro de La Loma, el corregimiento m\u00e1s grande de El Paso. Este municipio hace parte del Distrito Minero de La Jagua, que integra adem\u00e1s a Becerril, Agust\u00edn Codazzi, Chimichagua, Chiriguan\u00e1, Curuman\u00ed y La Jagua de Ibirico, y que, seg\u00fan datos de la Agencia Nacional de Miner\u00eda, produjo 3.025.662 toneladas de carb\u00f3n en 2018. Aunque la mina de El Hatillo fue concesionada en 1997 y, seg\u00fan recuerdan los pobladores, comenz\u00f3 a operar en 2007, solo hasta 2010 <strong>el Gobierno reconoci\u00f3 que su explotaci\u00f3n y el de las minas circundantes afectaba a la poblaci\u00f3n rural.<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cHa generado graves afectaciones a la salud y a la calidad de vida de los habitantes de los centros poblados ubicados en la zona de influencia de los proyectos mineros\u00bb<\/p><cite>ex Ministro de Ambiente.<\/cite><\/blockquote>\n\n\n\n<p>As\u00ed fue como en mayo de 2010, el Ministerio de Ambiente&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/es.scribd.com\/document\/404327772\/Resolucio-n-1525-del-5-de-agosto-de-2010?secret_password=eIPMQHdbTTk7cAEq6YLT\" target=\"_blank\">concluy\u00f3<\/a>&nbsp;\u2013al final del gobierno del presidente \u00c1lvaro Uribe- que el incremento en las emisiones de material particulado, que resulta de la miner\u00eda de carb\u00f3n, \u201cha generado graves afectaciones a la salud y a la calidad de vida de los habitantes de los centros poblados ubicados en la zona de influencia de los proyectos mineros\u201d. Junto con ese diagn\u00f3stico ven\u00eda una orden a las empresas mineras Prodeco, CNR, Drummond y Vale Coal de reasentar de inmediato a las poblaciones de Plan Bonito, Boquer\u00f3n y El Hatillo (Lea&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/es.scribd.com\/document\/404327754\/Resolucio-n-0970-del-20-de-mayo-de-2010?secret_password=j85wxm2cgjKzLXt7mF4J\" target=\"_blank\">Resoluci\u00f3n 0970 del 20 de mayo de 2010<\/a>).<\/p>\n\n\n\n<figure class=\"wp-block-image alignfull size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/tierra.jerre-dev.xyz\/wp-content\/uploads\/2019\/04\/CYD_6780-scaled.jpg\" alt=\"\" class=\"wp-image-4873\" srcset=\"https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211238\/CYD_6780-scaled.jpg 2560w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211238\/CYD_6780-300x200.jpg 300w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211238\/CYD_6780-1024x683.jpg 1024w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211238\/CYD_6780-768x512.jpg 768w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211238\/CYD_6780-1536x1024.jpg 1536w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211238\/CYD_6780-2048x1365.jpg 2048w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211238\/CYD_6780-150x100.jpg 150w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211238\/CYD_6780-696x464.jpg 696w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211238\/CYD_6780-1068x712.jpg 1068w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211238\/CYD_6780-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<p>Las mineras apelaron la decisi\u00f3n y en una nueva resoluci\u00f3n del 5 de agosto del mismo a\u00f1o el Ministerio reiter\u00f3 su orden perentoria, atribuyendo a cada minera porcentajes precisos de responsabilidad en el reasentamiento de las tres comunidades.&nbsp;<\/p>\n\n\n\n<p>Seg\u00fan la decisi\u00f3n del Gobierno, <strong>las empresas deb\u00edan financiar el proceso y contratar un operador para formular y luego ejecutar un Plan de Acci\u00f3n de Reasentamiento (PAR)<\/strong>, que incluyese un diagn\u00f3stico de la poblaci\u00f3n, un an\u00e1lisis regional y unas propuestas para el reasentamiento, adem\u00e1s de una interventor\u00eda que vigilara el proceso. El plazo para terminar el reasentamiento era de dos a\u00f1os, que<strong> vencieron en septiembre de 2012<\/strong> (Lea&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/es.scribd.com\/document\/404327772\/Resolucio-n-1525-del-5-de-agosto-de-2010?secret_password=eIPMQHdbTTk7cAEq6YLT\" target=\"_blank\">Resoluci\u00f3n 1525 del 5 de agosto 2010)<\/a>.<\/p>\n\n\n\n<p>Sin embargo, eso no ocurri\u00f3.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>La Secretar\u00eda de Salud de la Gobernaci\u00f3n del Cesar alert\u00f3 sobre el agua \u201cno apta para consumo humano\u201d de El Hatillo<\/p><\/blockquote>\n\n\n\n<p>En El Hatillo, los campesinos relatan que las empresas se demoraron en acatar las \u00f3rdenes del Ministerio y en garantizar la participaci\u00f3n de los habitantes. La ONG Pensamiento y Acci\u00f3n Social (PAS), que acompa\u00f1\u00f3 jur\u00eddicamente a la comunidad,&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/es.scribd.com\/document\/404327769\/Caracterizacio-n-El-Hatillo-PAS?secret_password=mQqvG4rPB4G3pXYOswqj\" target=\"_blank\">document\u00f3 que en marzo de 2011<\/a>&nbsp;<strong>el Ministerio impuso una medida preventiva de amonestaci\u00f3n escrita a las empresas por no haber contratado al operador.<\/strong> Un mes despu\u00e9s, la Secretar\u00eda de Salud de la Gobernaci\u00f3n del Cesar alert\u00f3 sobre el agua \u201cno apta para consumo humano\u201d de El Hatillo y sobre la prevalencia de enfermedades respiratorias, de piel y oculares en el 51,48 por ciento de la poblaci\u00f3n local.<\/p>\n\n\n\n<p><a href=\"https:\/\/es.scribd.com\/document\/404327759\/Informe-de-gestio-n-Anla?secret_password=e6YonvMrHQ0vIcBRg3mN\">Tras la amonestaci\u00f3n<\/a>, las empresas mineras contrataron a mediados de 2011 al Fondo Nacional de Desarrollo (Fonade) del Gobierno central como operador del plan y a la Corporaci\u00f3n para Estudios Interdisciplinarios y Asesor\u00eda T\u00e9cnica (Cetec), una organizaci\u00f3n sin \u00e1nimo de lucro de Cali, como interventora. En el Hatillo, la comunidad decidi\u00f3 organizarse para comenzar a negociar el llamado Plan de Acci\u00f3n Reasentamiento (PAR), de manera que en abril de 2012 crearon un Comit\u00e9 de Concertaci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Una angustia permanente<\/h2>\n\n\n\n<p>Para los hatillanos, <strong>el anuncio de la negociaci\u00f3n del reasentamiento coincidi\u00f3 con el inicio de la intranquilidad.<\/strong><\/p>\n\n\n\n<p>&nbsp;Cuando la noticia de la concertaci\u00f3n con las mineras corri\u00f3, cuentan los pobladores, llegaron a El Hatillo personas de afuera a comprar peque\u00f1os lotes en el poblado que les permitir\u00edan beneficiarse de las compensaciones que tendr\u00edan que hacer las empresas mineras. \u201cAparecieron 180 solares nuevos\u201d, coinciden los campesinos.<\/p>\n\n\n\n<p><strong>Luego, vinieron las amenazas<\/strong>.<\/p>\n\n\n\n<figure><iframe loading=\"lazy\" width=\"480\" height=\"270\" src=\"https:\/\/www.youtube.com\/embed\/65WyJNPy3tw?feature=oembed\" allowfullscreen=\"\"><\/iframe><\/figure>\n\n\n\n<p>En junio de 2014, el entonces gerente de la Cooperativa de Trabajadores Multiactivos de la Vereda El Hatillo recibi\u00f3 varias llamadas telef\u00f3nicas amenazantes. En septiembre del mismo a\u00f1o aparecieron panfletos amenazando a los l\u00edderes de la comunidad por la demora en el proceso de reasentamiento. En diciembre, se reanudaron las llamadas al gerente de la cooperativa, inst\u00e1ndolo a retirarse de la negociaci\u00f3n.<\/p>\n\n\n\n<p>Durante 2015 esas llamadas se extendieron a otros miembros de la junta de acci\u00f3n comunal y del Comit\u00e9 de Concertaci\u00f3n, que participaban en las reuniones del plan de reasentamiento. A esto se sumaron los mensajes de texto y los seguimientos por parte de desconocidos en moto, <strong>situaciones que llevaron a la comunidad a instalar alarmas en las casas de los l\u00edderes.<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abSe sent\u00eda mucho miedo por la presi\u00f3n que ten\u00edamos de parte de ellos, era una presi\u00f3n constante\u00bb.<\/p><\/blockquote>\n\n\n\n<p>\u201cEste proceso tuvo muchos ojos encima y las amenazas vinieron alrededor de que somos dos grupos: residentes y no residentes. Entonces cuando pele\u00e1bamos por el proceso de residentes, no pele\u00e1bamos por el proceso de los no residentes. Se sent\u00eda mucho miedo por la presi\u00f3n que ten\u00edamos de parte de ellos, era una presi\u00f3n constante\u201d, recuerda uno de los integrantes del Comit\u00e9.<\/p>\n\n\n\n<p><strong>Quienes participaron en la negociaci\u00f3n aseguran que los a\u00f1os m\u00e1s cr\u00edticos fueron los \u00faltimos tres.<\/strong> Sent\u00edan angustia cada vez que se sentaban en la mesa, cuentan varios miembros del Comit\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image alignfull size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/tierra.jerre-dev.xyz\/wp-content\/uploads\/2019\/04\/CYD_7367-scaled.jpg\" alt=\"\" class=\"wp-image-4879\" srcset=\"https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211221\/CYD_7367-scaled.jpg 2560w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211221\/CYD_7367-300x200.jpg 300w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211221\/CYD_7367-1024x683.jpg 1024w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211221\/CYD_7367-768x512.jpg 768w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211221\/CYD_7367-1536x1024.jpg 1536w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211221\/CYD_7367-2048x1365.jpg 2048w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211221\/CYD_7367-150x100.jpg 150w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211221\/CYD_7367-696x464.jpg 696w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211221\/CYD_7367-1068x712.jpg 1068w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211221\/CYD_7367-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<p>La demora en firmar no era un capricho personal, explican, sino que <strong>para ellos primaba la importancia de lograr acuerdos sobre temas fundamentales para la comunidad como el acceso a tierras, vivienda y proyectos productivos.<\/strong><\/p>\n\n\n\n<p>&nbsp;Entre tanto, otros atrasos se debieron a que las empresas mineras cambiaron varias veces de aliados locales. Para 2015 el contrato de ejecuci\u00f3n hab\u00eda pasado de Fonade a rePlan y por \u00faltimo a Socya, una instituci\u00f3n privada sin \u00e1nimo de lucro. El de interventor\u00eda pas\u00f3 de Cetec a Environmental Resources Management (ERM), una empresa de consultor\u00eda ambiental.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Los locales exig\u00edan el cumplimiento de sus derechos a la vida, la vivienda digna, la salud, el territorio y la alimentaci\u00f3n campesina, haciendo \u00e9nfasis en el riesgo que sufr\u00edan los l\u00edderes en ese momento.<\/p><\/blockquote>\n\n\n\n<p>En julio de 2016, hombres que se movilizaban en moto y con los rostros cubiertos continuaron merodeando las casas de los l\u00edderes, quienes siguieron recibiendo mensajes de texto con amenazas de muerte y se\u00f1alamientos de estar retrasando el proceso de reasentamiento. <strong>Las intimidaciones se recrudecieron despu\u00e9s de que, en noviembre de ese a\u00f1o, la comunidad del Hatillo interpuso&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/es.scribd.com\/document\/404327764\/Accio-n-de-tutela?secret_password=37wZzzib7OhAXnOjZr9F\" target=\"_blank\">una acci\u00f3n de tutela<\/a>&nbsp;contra Drummond, Prodeco y CNR<\/strong>, las tres empresas que quedaron a cargo del reasentamiento despu\u00e9s de que Vale Coal vendi\u00f3 la mina El Hatillo a CNR.<\/p>\n\n\n\n<p>En su tutela, los locales exig\u00edan el cumplimiento de sus derechos a la vida, la vivienda digna, la salud, el territorio y la alimentaci\u00f3n campesina, haciendo \u00e9nfasis en el riesgo que sufr\u00edan los l\u00edderes en ese momento. \u201cEn la actualidad, <strong>11 l\u00edderes y lideresas del proceso de reasentamiento han sufrido amenazas contra su integridad y su vida y las de sus grupos familiares<\/strong>. Todo lo anterior en consecuencia de su actividad como representantes de los Comit\u00e9s de Concertaci\u00f3n y Transici\u00f3n en el proceso de reasentamiento de la vereda El Hatillo\u201d, se\u00f1alaron en su acci\u00f3n jur\u00eddica.<\/p>\n\n\n\n<figure><iframe loading=\"lazy\" width=\"480\" height=\"270\" src=\"https:\/\/www.youtube.com\/embed\/kMDsEJTvGkk?feature=oembed\" allowfullscreen=\"\"><\/iframe><\/figure>\n\n\n\n<p>Ese final de 2016 fue una pesadilla para los l\u00edderes. En las noches comenzaron a ver hombres armados y vestidos de negro, con botas de caucho y pasamonta\u00f1as, que rondaban por las calles y cerca de sus casas. Continuaron las llamadas a los miembros del Comit\u00e9, incluido al \u00fanico integrante que hasta entonces no hab\u00eda recibido amenazas. &nbsp;<\/p>\n\n\n\n<p><strong>Lo que exacerb\u00f3 el miedo de la comunidad fue el&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/verdadabierta.com\/alerta-comunidad-de-el-hatillo-en-cesar-esta-en-riesgo\/\" target=\"_blank\">asesinato<\/a>&nbsp;de Aldemar Parra Garc\u00eda<\/strong>, el 7 de enero de 2017, en la v\u00eda que comunica hacia el corregimiento de La Loma. Un par de sicarios que se movilizaba en una moto de color rojo, sin placas y de marca Discover, le dispar\u00f3 cuatro veces.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Aldemar, de 31 a\u00f1os, no hab\u00eda recibido amenazas, pero su liderazgo era reconocido por la comunidad.<\/p><\/blockquote>\n\n\n\n<p>Amigos y familiares cuentan que Aldemar, de 31 a\u00f1os, no hab\u00eda recibido amenazas, pero su liderazgo era reconocido por la comunidad. Aunque no hac\u00eda parte del Comit\u00e9 de Concertaci\u00f3n, <strong>desde el liderazgo comunitario impulsaba la mesa de empleo<\/strong>, exigi\u00e9ndole a las empresas mineras que operan en el territorio oportunidades laborales para los hatillanos.<\/p>\n\n\n\n<p>La comunidad cuenta que Aldemar era sindicalista, hab\u00eda trabajado como analista de carb\u00f3n para CNR y buscaba un acuerdo econ\u00f3mico con esa empresa. Seg\u00fan explican, una gran parte de los antiguos trabajadores de CNR fue despedida en 2015, cuando la compa\u00f1\u00eda fue comprada por Murray Enery Corp. Pero <strong>Parra no quiso firmar la liquidaci\u00f3n, argumentando que el trabajo hab\u00eda tenido efectos en su salud y exigiendo una indemnizaci\u00f3n justa por ello<\/strong>.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Parra insist\u00eda en la necesidad de generar empleo para la comunidad<\/p><\/blockquote>\n\n\n\n<p>Su esposa Leanis Su\u00e1rez explica que, mientras llegaba a un acuerdo econ\u00f3mico con la empresa, <strong>Aldemar hab\u00eda decidido sacar adelante la Asociaci\u00f3n Ap\u00edcola del Cesar (Asograve)<\/strong>, una iniciativa que se gest\u00f3 en los cursos sobre proyectos productivos ofrecidos por el Programa de las Naciones Unidas para el Desarrollo (Pnud). Parra insist\u00eda en la necesidad de generar empleo para la comunidad. \u201cA \u00e9l le gustaba mucho trabajar en ese proyecto. En diciembre sacaron una buena cantidad de miel, 17 pimpinas, de la cual, sacando cuentas, \u00e9l dec\u00eda que les iba bien, porque a una pimpina le estaban sacando casi un mill\u00f3n de pesos\u201d, dice Su\u00e1rez.<\/p>\n\n\n\n<figure><iframe loading=\"lazy\" width=\"480\" height=\"270\" src=\"https:\/\/www.youtube.com\/embed\/y5lflXZW_b0?feature=oembed\" allowfullscreen=\"\"><\/iframe><\/figure>\n\n\n\n<p>Al preguntar a CNR sobre cu\u00e1l era la situaci\u00f3n laboral de Parra, la empresa respondi\u00f3 -por intermedio del Equipo T\u00e9cnico de Reasentamiento de las empresas mineras- que era empleado de la compa\u00f1\u00eda y estaba afiliado a un sindicato de la industria minera. \u201cAl momento de su muerte, llevaba varios a\u00f1os sin trabajar en la mina debido a recomendaci\u00f3n m\u00e9dica, aunque se manten\u00eda su contrataci\u00f3n vigente. No exist\u00eda una demanda laboral contra la empresa\u201d, se\u00f1ala. &nbsp;<\/p>\n\n\n\n<p>Las empresas consideran que Aldemar no represent\u00f3 un liderazgo en el proceso de reasentamiento.&nbsp;<\/p>\n\n\n\n<p>\u201cDesde el Equipo T\u00e9cnico de Reasentamiento y las Empresas Mineras no se evidenci\u00f3 una participaci\u00f3n activa del se\u00f1or Aldemar Garc\u00eda en el proceso de reasentamiento, salvo por su involucramiento en el proyecto ap\u00edcola desarrollado con el Pnud. Por tal motivo, no se podr\u00eda asegurar que fue un l\u00edder en el proceso y no podemos asegurar que su muerte pueda ser atribuible de manera directa o indirecta al proceso de reasentamiento, teniendo en cuenta que su caso a\u00fan se encuentra en investigaci\u00f3n\u201d, se\u00f1alaron las empresas&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/es.scribd.com\/document\/404327719\/Respuesta-Empresas-Mineras?secret_password=kadeTksGgiWZp5obHTIZ\" target=\"_blank\">en una respuesta conjunta el 22 de marzo<\/a>, despu\u00e9s de consultarles sobre la situaci\u00f3n laboral de Aldemar y sus acciones sobre la situaci\u00f3n de riesgo de los l\u00edderes de la comunidad.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abHubo tanta presi\u00f3n que algunos compa\u00f1eros se retiraron\u00bb<\/p><\/blockquote>\n\n\n\n<p>En El Hatillo solo hay preguntas sobre ese crimen y sobre las amenazas que arreciaron durante todo el 2017 y el 2018, hasta que en noviembre pasado lograron firmar el PAR.<\/p>\n\n\n\n<figure class=\"wp-block-image alignfull size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/tierra.jerre-dev.xyz\/wp-content\/uploads\/2019\/04\/CYD_7366-scaled.jpg\" alt=\"\" class=\"wp-image-4878\" srcset=\"https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211223\/CYD_7366-scaled.jpg 2560w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211223\/CYD_7366-300x200.jpg 300w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211223\/CYD_7366-1024x683.jpg 1024w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211223\/CYD_7366-768x512.jpg 768w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211223\/CYD_7366-1536x1024.jpg 1536w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211223\/CYD_7366-2048x1365.jpg 2048w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211223\/CYD_7366-150x100.jpg 150w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211223\/CYD_7366-696x464.jpg 696w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211223\/CYD_7366-1068x712.jpg 1068w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211223\/CYD_7366-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<p>\u201c<strong>Las presiones eran much\u00edsimas<\/strong>, uno lloraba. Est\u00e1bamos en una reuni\u00f3n para prepararnos, antes de llegar a la mesa, para defenderse ante las empresas porque la negociaci\u00f3n era empresa-comunidad, cuando nos llamaban y nos dec\u00edan que nos iban a picar los hijos, que sab\u00edan d\u00f3nde estudiaban. Hubo tanta presi\u00f3n que algunos compa\u00f1eros se retiraron\u201d, cuenta un l\u00edder.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cYa no nos quer\u00edan recibir las denuncias en la Fiscal\u00eda de Chiriguan\u00e1 ni en Bosconia\u201d<\/p><\/blockquote>\n\n\n\n<p>Los miembros del Comit\u00e9 de Concertaci\u00f3n concuerdan en que ese periodo fue el m\u00e1s tenso porque en \u00e9l se abordaron los aspectos m\u00e1s estructurales del reasentamiento, como el de acceso a tierras, vivienda y proyectos productivos. Varios <strong>reconocen que las empresas dispusieron transporte y presencia del Ej\u00e9rcito para garantizar su movilidad segura hasta las mesas de reuni\u00f3n<\/strong>. Sin embargo, <strong>las autoridades no investigaron qui\u00e9nes eran los autores de las amenazas ni los hostigamientos<\/strong> y \u2013seg\u00fan cuenta uno de los l\u00edderes- \u201cya no nos quer\u00edan recibir las denuncias en la Fiscal\u00eda de Chiriguan\u00e1 ni en Bosconia\u201d, dos municipios vecinos en el Cesar.<\/p>\n\n\n\n<p>Tras m\u00e1s de 200 mesas de trabajo y de una negociaci\u00f3n sobre 151 puntos, el 29 de noviembre de 2018 la comunidad y las empresas mineras firmaron el PAR. Despu\u00e9s de seis a\u00f1os de negociaci\u00f3n, ocho de los once l\u00edderes del Comit\u00e9 de Concertaci\u00f3n recibieron medidas de protecci\u00f3n por las amenazas. <strong>Varios creen que la angustia y la presi\u00f3n de tantos a\u00f1os tuvo efectos sobre la salud de los l\u00edderes Alberto Mej\u00eda y Alfonso Mart\u00ednez, quienes fallecieron por enfermedad durante ese per\u00edodo.<\/strong> Otros decidieron desplazarse a otras ciudades por temor, agotamiento y la incertidumbre sobre las garant\u00edas de seguridad de los pr\u00f3ximos a\u00f1os.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Del plan de papel al reasentamiento real<\/h2>\n\n\n\n<p>Para los hatillanos, en noviembre pasado comenz\u00f3 un nuevo proceso que no est\u00e1 exento de nuevos riesgos.<\/p>\n\n\n\n<p>De las 191 familias que integran originalmente la comunidad, ya 111 hab\u00edan expresado participar del reasentamiento colectivo, lo que significa que<strong> las empresas mineras deben construirles un nuevo centro poblado en otro lugar.<\/strong> El predio donde proyectan ese reasentamiento se llama Mata de Palma, tendr\u00e1 400 hect\u00e1reas, est\u00e1 ubicado en el vecino corregimiento de Potrerillo y actualmente est\u00e1 en proceso de compra. <strong>Adem\u00e1s de las viviendas, la infraestructura vial y el acceso a servicios p\u00fablicos, cada familia deber\u00e1 recibir un proyecto productivo.<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cEl riesgo sigue porque ahora es exigir que nos cumplan\u201d<\/p><\/blockquote>\n\n\n\n<p>A las otras 80 familias que han manifestado su preferencia por un reasentamiento individual, las empresas deber\u00e1n garantizarles la compra de una vivienda en el lugar donde quieren reconstruir sus vidas y un proyecto productivo.<\/p>\n\n\n\n<p>\u201cEl riesgo sigue porque ahora es exigir que nos cumplan\u201d, repiten varios miembros del Comit\u00e9.<\/p>\n\n\n\n<p>Seg\u00fan el PAR, las empresas tendr\u00e1n un plazo de cinco a\u00f1os en el ahora llamado Plan de Transici\u00f3n, por lo que<strong> la comunidad espera que esta vez s\u00ed tenga acompa\u00f1amiento del Estado.<\/strong><\/p>\n\n\n\n<figure><iframe loading=\"lazy\" width=\"480\" height=\"270\" src=\"https:\/\/www.youtube.com\/embed\/zpDAqMcabYE?feature=oembed\" allowfullscreen=\"\"><\/iframe><\/figure>\n\n\n\n<p>\u201cEl Plan de Transici\u00f3n nos preocupa, porque el traslado significa que en realidad debe mejorar la calidad de vida de la comunidad\u201d, dice Jesualdo Vega, secretario de la Junta de Acci\u00f3n Comunal.<\/p>\n\n\n\n<p>Aunque la negociaci\u00f3n entre la comunidad y las empresas comenz\u00f3 en 2012, el Ministerio de Minas y Energ\u00eda reconoce que desde febrero de 2017 viene acompa\u00f1ando las mesas de concertaci\u00f3n del PAR y que \u201cmantiene su compromiso de acompa\u00f1ar el proceso en su fase de implementaci\u00f3n\u201d. Sin embargo,&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/es.scribd.com\/document\/404327721\/Respuesta-Ministerio-de-Minas-y-Energi-a?secret_password=mHthKDw9FCb6pdHYalCX\" target=\"_blank\">en respuesta a una solicitud de informaci\u00f3n<\/a>&nbsp;el Ministerio aclara que, como el reasentamiento es producto de resoluciones del Ministerio de Ambiente, <strong>\u201ccorresponde a las autoridades ambientales exigir el cumplimiento de lo acordado en el Plan de Reasentamiento y derivados del proceso de licenciamiento\u201d<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image alignfull size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/tierra.jerre-dev.xyz\/wp-content\/uploads\/2019\/04\/CYD_6854-scaled.jpg\" alt=\"\" class=\"wp-image-4875\" srcset=\"https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211232\/CYD_6854-scaled.jpg 2560w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211232\/CYD_6854-300x200.jpg 300w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211232\/CYD_6854-1024x683.jpg 1024w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211232\/CYD_6854-768x512.jpg 768w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211232\/CYD_6854-1536x1024.jpg 1536w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211232\/CYD_6854-2048x1365.jpg 2048w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211232\/CYD_6854-150x100.jpg 150w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211232\/CYD_6854-696x464.jpg 696w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211232\/CYD_6854-1068x712.jpg 1068w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211232\/CYD_6854-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<p>Desde el 4 de marzo solicitamos informaci\u00f3n de forma verbal y por escrito al Ministerio de Ambiente y Desarrollo Sostenible sobre su compromiso en acompa\u00f1ar a la comunidad de El Hatillo en la implementaci\u00f3n del PAR y en exigir cumplimiento a las empresas mineras sobre los acuerdos. Sin embargo, al cierre de la historia no hemos recibido respuesta de la instituci\u00f3n (<a rel=\"noreferrer noopener\" href=\"https:\/\/es.scribd.com\/document\/404327706\/Solicitud-de-versio-n-Ministerio-de-Ambiente?secret_password=kKdkIp08IFOGsSBmOt9s\" target=\"_blank\">Ver preguntas enviadas al Ministerio de Ambiente<\/a>)&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cEl Plan de Transici\u00f3n nos preocupa, porque el traslado significa que en realidad debe mejorar la calidad de vida de la comunidad\u201d<\/p><cite>Jesualdo Vega<\/cite><\/blockquote>\n\n\n\n<p>Sobre la situaci\u00f3n de riesgo de los l\u00edderes sociales, <strong>el Ministerio de Minas y Energ\u00eda indica que formul\u00f3 una pol\u00edtica de Derechos Humanos del Sector Minero-Energ\u00e9tico<\/strong> y que en la actualidad desarrolla planes de acci\u00f3n para su implementaci\u00f3n. Tambi\u00e9n que participa del Grupo de Trabajo de Derechos Humanos y Carb\u00f3n, que firm\u00f3 una declaraci\u00f3n conjunta de rechazo a las amenazas a la vida e integridad de las personas, con el apoyo de las organizaciones de la sociedad civil como el Centro Regional de Empresas y Emprendimientos Responsables (CREER-IHRB) y la Fundaci\u00f3n Ideas para la Paz (Lea&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/es.scribd.com\/document\/404327721\/Respuesta-Ministerio-de-Minas-y-Energi-a?secret_password=mHthKDw9FCb6pdHYalCX\" target=\"_blank\">respuesta del Ministerio de Minas<\/a>).<\/p>\n\n\n\n<p>El Grupo est\u00e1 integrado por la Consejer\u00eda de Derechos Humanos, el Ministerio de Minas, la Agencia Nacional de Miner\u00eda y las empresas Cerrej\u00f3n, Drummond, Prodeco y CNR, que trabajan en la formulaci\u00f3n de un \u201cProcedimiento para la activaci\u00f3n de ruta para la protecci\u00f3n de la vida e integridad personal de grupos de inter\u00e9s\u201d. &nbsp;<\/p>\n\n\n\n<p>Al preguntar a Drummond, Prodeco y CNR sobre las acciones que tomaron para responder las situaciones de amenaza o riesgo de los l\u00edderes de El Hatillo, <strong>explicaron que sugirieron a los afectados presentar las denuncias, en varios casos los acompa\u00f1aron a instaurarlas y desarrollaron talleres en competencias de seguridad, dirigidas a los representantes de la comunidad<\/strong>, con el Programa de Desarrollo y Paz del Cesar.<\/p>\n\n\n\n<figure class=\"wp-block-image alignfull size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/tierra.jerre-dev.xyz\/wp-content\/uploads\/2019\/04\/CYD_7092-scaled.jpg\" alt=\"\" class=\"wp-image-4876\" srcset=\"https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211228\/CYD_7092-scaled.jpg 2560w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211228\/CYD_7092-300x200.jpg 300w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211228\/CYD_7092-1024x683.jpg 1024w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211228\/CYD_7092-768x512.jpg 768w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211228\/CYD_7092-1536x1024.jpg 1536w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211228\/CYD_7092-2048x1365.jpg 2048w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211228\/CYD_7092-150x100.jpg 150w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211228\/CYD_7092-696x464.jpg 696w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211228\/CYD_7092-1068x712.jpg 1068w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211228\/CYD_7092-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<p>\u201cIgualmente, se cont\u00f3 con la participaci\u00f3n de entidades como Ej\u00e9rcito Nacional, Polic\u00eda Nacional y la Unidad Nacional de Protecci\u00f3n (UNP), quienes<strong> intensificaron sus unidades en la zona para acercar y brindar una mayor protecci\u00f3n a la poblaci\u00f3n de El Hatillo<\/strong>. As\u00ed mismo, en cada una de las ocasiones en donde era demostrable la amenaza a los representantes o miembros de la Junta de Acci\u00f3n Comunal, las Empresas Mineras enviaron comunicados de prensa, rechazando los hechos\u201d, respondieron las tres empresas en un documento conjunto, que lleva sus tres logos y a nombre del Equipo T\u00e9cnico de Reasentamientos liderado por Jos\u00e9 Link.&nbsp;<\/p>\n\n\n\n<p>Frente a las garant\u00edas de seguridad ahora en el proceso de transici\u00f3n, las tres empresas mineras se\u00f1alan que la fortaleza del proceso pactado en 2018 es que involucra al menos dos Ministerios y tres agencias del Gobierno central, adem\u00e1s de la Defensor\u00eda del Pueblo y los gobiernos regional y local. \u00abAlgunos de estos actores seguir\u00e1n presentes durante el proceso de traslado y posterior acompa\u00f1amiento de la comunidad en su sitio de reasentamiento\u00bb, afirman.<\/p>\n\n\n\n<figure><iframe loading=\"lazy\" width=\"480\" height=\"270\" src=\"https:\/\/www.youtube.com\/embed\/kCWCOWlBYT4?feature=oembed\" allowfullscreen=\"\"><\/iframe><\/figure>\n\n\n\n<p>Sin embargo, subrayan que -a su juicio- el nivel de riesgo de las comunidades no ha aumentado, sino disminuido. \u00ab<strong>Cabe indicar que el riesgo que pueden vivir las familias de El Hatillo en el per\u00edodo de transici\u00f3n probablemente no ser\u00e1 mayor al que han vivido hasta ahora<\/strong>, pues los riesgos est\u00e1n relacionados con la situaci\u00f3n de falta de seguridad que vive la regi\u00f3n y el pa\u00eds, por m\u00faltiples causas\u00bb, se\u00f1alan, a\u00f1adiendo que han propiciado reuniones de la comunidad con la Consejer\u00eda de Seguridad del presidente Iv\u00e1n Duque, la Unidad Nacional de Protecci\u00f3n (UNP) y las polic\u00edas locales (<a rel=\"noreferrer noopener\" href=\"https:\/\/es.scribd.com\/document\/404327719\/Respuesta-Empresas-Mineras?secret_password=kadeTksGgiWZp5obHTIZ\" target=\"_blank\">Lea las respuestas completas de las empresas<\/a>).&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abLos riesgos est\u00e1n relacionados con la situaci\u00f3n de falta de seguridad que vive la regi\u00f3n y el pa\u00eds, por m\u00faltiples causas\u00bb.<\/p><cite>Equipo T\u00e9cnico de Reasentamientos liderado por Jos\u00e9 Link<\/cite><\/blockquote>\n\n\n\n<p><strong>En El Hatillo han sido las empresas mineras las que han fungido como Estado y la incertidumbre se debe a que una vez firmado el PAR, por ejemplo, al pueblo no volvieron el profesor de educaci\u00f3n f\u00edsica ni la enfermera.<\/strong> Ambos eran pagados por las compa\u00f1\u00edas.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image alignfull size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/tierra.jerre-dev.xyz\/wp-content\/uploads\/2019\/04\/CYD_6750-scaled.jpg\" alt=\"\" class=\"wp-image-4871\" srcset=\"https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211246\/CYD_6750-scaled.jpg 2560w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211246\/CYD_6750-300x200.jpg 300w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211246\/CYD_6750-1024x683.jpg 1024w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211246\/CYD_6750-768x512.jpg 768w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211246\/CYD_6750-1536x1024.jpg 1536w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211246\/CYD_6750-2048x1365.jpg 2048w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211246\/CYD_6750-150x100.jpg 150w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211246\/CYD_6750-696x464.jpg 696w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211246\/CYD_6750-1068x712.jpg 1068w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211246\/CYD_6750-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<p>A marzo de 2019 ya se hab\u00edan realizado tres mesas para comenzar el proceso de transici\u00f3n. Con incertidumbre, <strong>esperan que existan condiciones de seguridad para lograr el reasentamiento, que las becas de estudio universitario, t\u00e9cnico y tecnol\u00f3gico acordadas con las empresas mineras les permitan tener los primeros profesionales durante los siguientes 11 a\u00f1os<\/strong> y, sobre todo, que su lucha por no respirar carb\u00f3n haya valido la pena. &nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tierra.jerre-dev.xyz\/wp-content\/uploads\/2021\/03\/eee.png\" alt=\"Tierra de Resistentes\" class=\"wp-image-3766\" width=\"100\" height=\"100\" srcset=\"https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2021\/03\/19211834\/eee.png 400w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2021\/03\/19211834\/eee-300x300.png 300w, https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2021\/03\/19211834\/eee-150x150.png 150w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En el departamento de Cesar, en el nororiente colombiano, una comunidad campesina lleva casi una d\u00e9cada esperando ser reasentada a causa de la contaminaci\u00f3n generada por las minas aleda\u00f1as. En los \u00faltimos cuatro a\u00f1os, un l\u00edder fue asesinado y ocho m\u00e1s han recibido amenazas.<\/p>\n","protected":false},"author":19,"featured_media":4874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[2],"tags":[155,301,45,96,303,302],"coauthors":[197],"class_list":{"0":"post-50","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-colombia","8":"tag-agua","9":"tag-carbon","10":"tag-fase-i","11":"tag-mineria","12":"tag-palma-de-cera","13":"tag-reasentamiento"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Hatillo, la tensa lucha por no respirar carb\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tierraderesistentes.com\/es\/2019\/04\/17\/el-hatillo-la-tensa-lucha-por-no-respirar-carbon\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ivonne Rodr\u00edguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"66 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Hatillo, la tensa lucha por no respirar carb\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tierraderesistentes.com\/es\/2019\/04\/17\/el-hatillo-la-tensa-lucha-por-no-respirar-carbon\/","twitter_misc":{"Written by":"Ivonne Rodr\u00edguez","Est. reading time":"66 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tierraderesistentes.com\/es\/2019\/04\/17\/el-hatillo-la-tensa-lucha-por-no-respirar-carbon\/#article","isPartOf":{"@id":"https:\/\/tierraderesistentes.com\/es\/2019\/04\/17\/el-hatillo-la-tensa-lucha-por-no-respirar-carbon\/"},"author":{"name":"Ivonne Rodr\u00edguez","@id":"https:\/\/tierraderesistentes.com\/es\/#\/schema\/person\/380ad3c5be98d0555ab6cd60b1c4659b"},"headline":"El Hatillo, la tensa lucha por no respirar carb\u00f3n","datePublished":"2019-04-17T20:13:00+00:00","dateModified":"2021-05-01T20:01:42+00:00","mainEntityOfPage":{"@id":"https:\/\/tierraderesistentes.com\/es\/2019\/04\/17\/el-hatillo-la-tensa-lucha-por-no-respirar-carbon\/"},"wordCount":13205,"commentCount":16,"publisher":{"@id":"https:\/\/tierraderesistentes.com\/es\/#organization"},"image":{"@id":"https:\/\/tierraderesistentes.com\/es\/2019\/04\/17\/el-hatillo-la-tensa-lucha-por-no-respirar-carbon\/#primaryimage"},"thumbnailUrl":"https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211234\/CYD_6825-scaled.jpg","keywords":["agua","carb\u00f3n","Fase I","miner\u00eda","palma de cera","reasentamiento"],"articleSection":["Colombia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tierraderesistentes.com\/es\/2019\/04\/17\/el-hatillo-la-tensa-lucha-por-no-respirar-carbon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tierraderesistentes.com\/es\/2019\/04\/17\/el-hatillo-la-tensa-lucha-por-no-respirar-carbon\/","url":"https:\/\/tierraderesistentes.com\/es\/2019\/04\/17\/el-hatillo-la-tensa-lucha-por-no-respirar-carbon\/","name":"El Hatillo, la tensa lucha por no respirar carb\u00f3n","isPartOf":{"@id":"https:\/\/tierraderesistentes.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tierraderesistentes.com\/es\/2019\/04\/17\/el-hatillo-la-tensa-lucha-por-no-respirar-carbon\/#primaryimage"},"image":{"@id":"https:\/\/tierraderesistentes.com\/es\/2019\/04\/17\/el-hatillo-la-tensa-lucha-por-no-respirar-carbon\/#primaryimage"},"thumbnailUrl":"https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211234\/CYD_6825-scaled.jpg","datePublished":"2019-04-17T20:13:00+00:00","dateModified":"2021-05-01T20:01:42+00:00","breadcrumb":{"@id":"https:\/\/tierraderesistentes.com\/es\/2019\/04\/17\/el-hatillo-la-tensa-lucha-por-no-respirar-carbon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tierraderesistentes.com\/es\/2019\/04\/17\/el-hatillo-la-tensa-lucha-por-no-respirar-carbon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tierraderesistentes.com\/es\/2019\/04\/17\/el-hatillo-la-tensa-lucha-por-no-respirar-carbon\/#primaryimage","url":"https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211234\/CYD_6825-scaled.jpg","contentUrl":"https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2019\/04\/19211234\/CYD_6825-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/tierraderesistentes.com\/es\/2019\/04\/17\/el-hatillo-la-tensa-lucha-por-no-respirar-carbon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tierraderesistentes.com\/es\/"},{"@type":"ListItem","position":2,"name":"El Hatillo, la tensa lucha por no respirar carb\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/tierraderesistentes.com\/es\/#website","url":"https:\/\/tierraderesistentes.com\/es\/","name":"Tierra de Resistentes | Consejo de Redacci\u00f3n","description":"Base de datos de defensores ambientales amenazados y asesinados en Latinoam\u00e9rica. Historias, fotograf\u00edas, videos y gr\u00e1ficos para entender la situaci\u00f3n de los resistentes.","publisher":{"@id":"https:\/\/tierraderesistentes.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tierraderesistentes.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tierraderesistentes.com\/es\/#organization","name":"Tierra de resistentes","url":"https:\/\/tierraderesistentes.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tierraderesistentes.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/tierraderesistentes.com\/wp-content\/uploads\/2021\/01\/LogoEspanolAjustado-1.png","contentUrl":"https:\/\/tierraderesistentes.com\/wp-content\/uploads\/2021\/01\/LogoEspanolAjustado-1.png","width":1568,"height":944,"caption":"Tierra de resistentes"},"image":{"@id":"https:\/\/tierraderesistentes.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tierraderesistentes.com\/es\/#\/schema\/person\/380ad3c5be98d0555ab6cd60b1c4659b","name":"Ivonne Rodr\u00edguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tierraderesistentes.com\/es\/#\/schema\/person\/image\/8bf1a0b683df20f01c712cb1540dfb70","url":"https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2021\/02\/19211953\/Ivonne-Rodriguez-150x150.jpg","contentUrl":"https:\/\/media.tierraderesistentes.com\/wp-content\/uploads\/2021\/02\/19211953\/Ivonne-Rodriguez-150x150.jpg","caption":"Ivonne Rodr\u00edguez"},"description":"Periodista de investigaci\u00f3n sobre el conflicto armado colombiano. Trabaj\u00f3 durante 9 a\u00f1os en VerdadAbierta.com, un portal especializado en la documentaci\u00f3n de los procesos de justicia transicional, con \u00e9nfasis en el despojo de tierras y territorios. Fue reportera en Votebien.com, Vanguardia Liberal y La Prensa.","url":"https:\/\/tierraderesistentes.com\/es\/author\/ivonne\/"}]}},"_links":{"self":[{"href":"https:\/\/tierraderesistentes.com\/es\/wp-json\/wp\/v2\/posts\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tierraderesistentes.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tierraderesistentes.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tierraderesistentes.com\/es\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/tierraderesistentes.com\/es\/wp-json\/wp\/v2\/comments?post=50"}],"version-history":[{"count":0,"href":"https:\/\/tierraderesistentes.com\/es\/wp-json\/wp\/v2\/posts\/50\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tierraderesistentes.com\/es\/wp-json\/wp\/v2\/media\/4874"}],"wp:attachment":[{"href":"https:\/\/tierraderesistentes.com\/es\/wp-json\/wp\/v2\/media?parent=50"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tierraderesistentes.com\/es\/wp-json\/wp\/v2\/categories?post=50"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tierraderesistentes.com\/es\/wp-json\/wp\/v2\/tags?post=50"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/tierraderesistentes.com\/es\/wp-json\/wp\/v2\/coauthors?post=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}