{"id":364,"count":1,"description":"","link":"https:\/\/tierraderesistentes.com\/en\/tag\/pemones\/","name":"pemones","slug":"pemones","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>pemones Archives | Tierra de Resistentes | Consejo de Redacci\u00f3n<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"pemones Archives | Tierra de Resistentes | Consejo de Redacci\u00f3n","robots":{"index":"noindex","follow":"follow"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/tierraderesistentes.com\/pt\/tag\/pemones\/","url":"https:\/\/tierraderesistentes.com\/pt\/tag\/pemones\/","name":"pemones Archives | Tierra de Resistentes | Consejo de Redacci\u00f3n","isPartOf":{"@id":"https:\/\/tierraderesistentes.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/tierraderesistentes.com\/pt\/tag\/pemones\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/tierraderesistentes.com\/pt\/tag\/pemones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tierraderesistentes.com\/es\/"},{"@type":"ListItem","position":2,"name":"pemones"}]},{"@type":"WebSite","@id":"https:\/\/tierraderesistentes.com\/es\/#website","url":"https:\/\/tierraderesistentes.com\/es\/","name":"Tierra de Resistentes | Consejo de Redacci\u00f3n","description":"Base de datos de defensores ambientales amenazados y asesinados en Latinoam\u00e9rica. Historias, fotograf\u00edas, videos y gr\u00e1ficos para entender la situaci\u00f3n de los resistentes.","publisher":{"@id":"https:\/\/tierraderesistentes.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tierraderesistentes.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/tierraderesistentes.com\/es\/#organization","name":"Tierra de resistentes","url":"https:\/\/tierraderesistentes.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tierraderesistentes.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/tierraderesistentes.com\/wp-content\/uploads\/2021\/01\/LogoEspanolAjustado-1.png","contentUrl":"https:\/\/tierraderesistentes.com\/wp-content\/uploads\/2021\/01\/LogoEspanolAjustado-1.png","width":1568,"height":944,"caption":"Tierra de resistentes"},"image":{"@id":"https:\/\/tierraderesistentes.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tierraderesistentes.com\/en\/wp-json\/wp\/v2\/tags\/364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tierraderesistentes.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tierraderesistentes.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tierraderesistentes.com\/en\/wp-json\/wp\/v2\/posts?tags=364"},{"href":"https:\/\/tierraderesistentes.com\/en\/wp-json\/wp\/v2\/pages?tags=364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}